{"id":2148,"date":"2021-10-07T16:00:39","date_gmt":"2021-10-07T14:00:39","guid":{"rendered":"https:\/\/gastro-brennecke.de\/blog\/?post_type=rezepturen&#038;p=2148"},"modified":"2026-04-12T16:39:15","modified_gmt":"2026-04-12T14:39:15","slug":"rumkugel-likoer","status":"publish","type":"post","link":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/","title":{"rendered":"Rumkugel Lik\u00f6r &#8211; der Anspruchsvolle"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2148\" class=\"elementor elementor-2148\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2eab5cc6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2eab5cc6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3392e546\" data-id=\"3392e546\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4be17c33 elementor-widget elementor-widget-heading\" data-id=\"4be17c33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Rumkugel Lik\u00f6r - der Anspruchsvolle <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-417564c5 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"417564c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r-1024x1024.jpg?wsr\" class=\"attachment-large size-large wp-image-4108\" alt=\"\" srcset=\"https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r-1024x1024.jpg 1024w, https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r-300x300.jpg 300w, https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r-150x150.jpg 150w, https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r-768x768.jpg 768w, https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a36f0e1 elementor-widget elementor-widget-text-editor\" data-id=\"1a36f0e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span dir=\"ltr\"><span class=\"NormalTextRun SCXW125531838 BCX0\">Ein besonderes Rezept f\u00fcr ein c<strong>remig-kr\u00e4ftiges Geschmackserlebnis<\/strong>. Die Zubereitung ist schon ein bisschen anspruchsvoll &#8211; schaff dir eine ungest\u00f6rte Arbeitsatmosph\u00e4re und konz<\/span><span class=\"NormalTextRun SCXW125531838 BCX0\">entriere dich f\u00fcr 30 Minuten voll auf deinen Lik\u00f6r.\u00a0<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-39673ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39673ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-67e5ffac\" data-id=\"67e5ffac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abacb48 elementor-widget elementor-widget-heading\" data-id=\"abacb48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Vorbereitungszeit:<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56e1c8f4 elementor-widget elementor-widget-heading\" data-id=\"56e1c8f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">5 Min.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3a961de7\" data-id=\"3a961de7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-341f1b01 elementor-widget elementor-widget-heading\" data-id=\"341f1b01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Zubereitungszeit:<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6368c49f elementor-widget elementor-widget-heading\" data-id=\"6368c49f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">30 Min.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6c7125bf\" data-id=\"6c7125bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ef1a26a elementor-widget elementor-widget-heading\" data-id=\"7ef1a26a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ergibt:<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e9a7596 elementor-widget elementor-widget-heading\" data-id=\"6e9a7596\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">ca. 1 Liter<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-513eac1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"513eac1c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a38706d\" data-id=\"1a38706d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d173ac elementor-widget elementor-widget-heading\" data-id=\"1d173ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Zutaten:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-325d2ea4 elementor-widget elementor-widget-text-editor\" data-id=\"325d2ea4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span data-contrast=\"auto\">250 Gramm Rumkugeln\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span data-contrast=\"auto\">40 Gramm brauner Zucker<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span data-contrast=\"auto\">1 P\u00e4ckchen Vanillezucker <\/span><\/li><li><span data-contrast=\"auto\">40 Gramm Zartbitterschokolade\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\"> <br \/><\/span><\/li><li><span data-contrast=\"auto\">400 Gramm Sahne<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span data-contrast=\"auto\">400 Gramm Milch<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span data-contrast=\"auto\">2 Eier<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span data-contrast=\"auto\">250 Gramm Rum<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><li><span data-contrast=\"auto\">200 Gramm Weinbrand<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ae7b6b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ae7b6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b57c4c9\" data-id=\"3b57c4c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aaf271f elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"3aaf271f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-utensil-spoon\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78640b03 elementor-widget elementor-widget-heading\" data-id=\"78640b03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zubereitung:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-613db475 elementor-widget elementor-widget-text-editor\" data-id=\"613db475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><span data-contrast=\"auto\">Zerkleinere zuerst die Rumkugeln mit einer Gabel. Verr\u00fchre sie anschlie\u00dfend mit einem Handr\u00fchrer oder P\u00fcrierstab so lange, bis du eine kompakte Creme erh\u00e4ltst. <\/span><\/li><li><span data-contrast=\"auto\">F\u00fclle nun die Creme in einen Topf und mische Zucker, Vanillezucker, Sahne, Milch und Eier mit einem Handr\u00fchrger\u00e4t unter. <\/span><\/li><li><span data-contrast=\"auto\">Erhitze jetzt die Creme unter st\u00e4ndigem R\u00fchren bei leichter\u00a0bis m\u00e4\u00dfiger Temperatur. Die Creme sollte nicht kochen, aber hei\u00df werden. <\/span><span data-contrast=\"auto\">R\u00fchre f\u00fcr ca. 5 Minuten bei hoher Temperatur weiter (bei ca. 80 Grad).<\/span><\/li><li><span data-contrast=\"auto\">Gib nun die Rum-Weinbrand-Mischung dazu und r\u00fchre diese gut unter. <\/span><\/li><li><span data-contrast=\"auto\">Jetzt kannst du den Lik\u00f6r in deine Flaschen f\u00fcllen, verschlie\u00dfen, abk\u00fchlen lassen und im K\u00fchlschrank lagern.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52b5d5c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52b5d5c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30fd37ff\" data-id=\"30fd37ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1874c30e elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"1874c30e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-thumbs-up\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69c3a382 elementor-widget elementor-widget-heading\" data-id=\"69c3a382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Empfehlungen:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6702f29f elementor-widget elementor-widget-text-editor\" data-id=\"6702f29f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"NormalTextRun  BCX0 SCXW91395009\"><strong>Achte unbedingt darauf, dass deine Mischung nicht kocht<\/strong> und w\u00e4hrend der gesamten Hitzephase ge<\/span><span class=\"NormalTextRun  BCX0 SCXW91395009\">r\u00fchrt wird. Das ist etwas m\u00fchsam und geht am besten mit einem Mixger\u00e4t, das gleichzeitig erhitzt. Aber: Wenn du keins hast, dann ist das kein Problem, es funktioniert auch ohne. Nimm dann auf jeden Fall einen Handmixer. Sollte die Creme zu\u00a0<\/span><span class=\"NormalTextRun  BCX0 SCXW91395009\">hei\u00df werden, dan<\/span><span class=\"NormalTextRun  BCX0 SCXW91395009\">n kannst du den Topf zwischendurch auch f\u00fcr ein paar Minuten von der Platte nehmen und weiterr\u00fchren.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4167f149 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4167f149\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ca81f00\" data-id=\"7ca81f00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d055a6b elementor-widget elementor-widget-post-navigation\" data-id=\"6d055a6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Beitrag Navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/gastro-brennecke.de\/blog\/likoer\/bratapfellikoer\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><i aria-hidden=\"true\" class=\"fas fa-angle-left\"><\/i><span class=\"elementor-screen-only\">Zur\u00fcck<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Previous<\/span><span class=\"post-navigation__prev--title\">Bratapfellik\u00f6r &#8211; der Klassiker<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/gastro-brennecke.de\/blog\/likoer\/nuss-schoko-likoer\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">Next<\/span><span class=\"post-navigation__next--title\">Nuss-Schoko-Lik\u00f6r &#8211; der Nussige<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i><span class=\"elementor-screen-only\">N\u00e4chster<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-543d416b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"543d416b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6418aa5e\" data-id=\"6418aa5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Rumkugel Lik\u00f6r &#8211; der Anspruchsvolle Ein besonderes Rezept f\u00fcr ein cremig-kr\u00e4ftiges Geschmackserlebnis. Die Zubereitung ist schon ein bisschen anspruchsvoll &#8211; schaff dir eine ungest\u00f6rte Arbeitsatmosph\u00e4re und konzentriere dich f\u00fcr 30 Minuten voll auf deinen Lik\u00f6r. Vorbereitungszeit: 5 Min. Zubereitungszeit: 30 Min. Ergibt: ca. 1 Liter Zutaten: 250 Gramm Rumkugeln 40 Gramm brauner Zucker 1 P\u00e4ckchen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4108,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76,128],"tags":[],"class_list":["post-2148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-likoer","category-likoer-rezepte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rumkugel Lik\u00f6r - der Anspruchsvolle - Gastro Brennecke Blog<\/title>\n<meta name=\"description\" content=\"Ohne Thermomix \u2713 Genial lecker \u2713 cremig-kr\u00e4ftiger Geschmack \u2713 Rezept \u2713 Den musst du probiert haben - hier dein Rezept!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rumkugel Lik\u00f6r - der Anspruchsvolle - Gastro Brennecke Blog\" \/>\n<meta property=\"og:description\" content=\"Ohne Thermomix \u2713 Genial lecker \u2713 cremig-kr\u00e4ftiger Geschmack \u2713 Rezept \u2713 Den musst du probiert haben - hier dein Rezept!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/\" \/>\n<meta property=\"og:site_name\" content=\"Gastro Brennecke Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gastrobrennecke\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-07T14:00:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-12T14:39:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nico Brennecke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GastroBrennecke\" \/>\n<meta name=\"twitter:site\" content=\"@GastroBrennecke\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nico Brennecke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/\"},\"author\":{\"name\":\"Nico Brennecke\",\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/#\\\/schema\\\/person\\\/f08b921dc43532d46c5935307f76c2d5\"},\"headline\":\"Rumkugel Lik\u00f6r &#8211; der Anspruchsvolle\",\"datePublished\":\"2021-10-07T14:00:39+00:00\",\"dateModified\":\"2026-04-12T14:39:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/\"},\"wordCount\":274,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Rumkugelliko\u0308r.jpg?wsr\",\"articleSection\":[\"Lik\u00f6r\",\"Lik\u00f6r Rezepte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/\",\"url\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/\",\"name\":\"Rumkugel Lik\u00f6r - der Anspruchsvolle - Gastro Brennecke Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Rumkugelliko\u0308r.jpg?wsr\",\"datePublished\":\"2021-10-07T14:00:39+00:00\",\"dateModified\":\"2026-04-12T14:39:15+00:00\",\"description\":\"Ohne Thermomix \u2713 Genial lecker \u2713 cremig-kr\u00e4ftiger Geschmack \u2713 Rezept \u2713 Den musst du probiert haben - hier dein Rezept!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Rumkugelliko\u0308r.jpg?wsr\",\"contentUrl\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Rumkugelliko\u0308r.jpg?wsr\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/likoer\\\/rumkugel-likoer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rumkugel Lik\u00f6r &#8211; der Anspruchsvolle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/\",\"name\":\"Gastro Brennecke Blog\",\"description\":\"Bier selber brauen | Schank &amp; Zapfanlagen - Gastro Brennecke\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/#organization\",\"name\":\"Gastro Brennecke Blog\",\"url\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/2020-brennecke-logo.png?wsr\",\"contentUrl\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/2020-brennecke-logo.png?wsr\",\"width\":462,\"height\":136,\"caption\":\"Gastro Brennecke Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gastrobrennecke\",\"https:\\\/\\\/x.com\\\/GastroBrennecke\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nico-brennecke-770a64217\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/bierbrauen\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/gastrokomplett\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/#\\\/schema\\\/person\\\/f08b921dc43532d46c5935307f76c2d5\",\"name\":\"Nico Brennecke\",\"pronouns\":\"er\\\/ihm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265753c7995506fcc19fd4b8a2ce9183d2515b32050fd9a3548bd671d9f7ca1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265753c7995506fcc19fd4b8a2ce9183d2515b32050fd9a3548bd671d9f7ca1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/265753c7995506fcc19fd4b8a2ce9183d2515b32050fd9a3548bd671d9f7ca1a?s=96&d=mm&r=g\",\"caption\":\"Nico Brennecke\"},\"description\":\"Ich bin Nico Brennecke, Experte f\u00fcr Hobbybrauen und Schanktechnik und Inhaber von Gastro Brennecke mit \u00fcber 15 Jahren Erfahrung. Unser Familienunternehmen besteht seit \u00fcber 40 Jahren und hat sich auf alles rund ums Bier brauen, Zapfanlagen und Ausschanktechnik spezialisiert. Vom Einsteiger bis zur Gastronomie unterst\u00fctze ich t\u00e4glich Kunden bei der Auswahl der passenden Technik und Zutaten. Besonders wichtig ist mir, dass unsere Produkte nicht nur verkauft, sondern auch verstanden werden. Deshalb findest du in unserer Wissenswelt, im Blog und im Lexikon zahlreiche Anleitungen, Tipps und Hintergrundwissen aus der Praxis. Durch meine Erfahrung aus tausenden Kundenprojekten wei\u00df ich genau, worauf es beim Bier brauen und beim perfekten Ausschank wirklich ankommt. Wenn du Fragen rund ums Bier brauen oder Zapfanlagen hast, findest du hier im Blog viele praktische Anleitungen aus der Praxis. Mehr \u00fcber mich erf\u00e4hrst du hier: Zur Expertenseite\",\"sameAs\":[\"https:\\\/\\\/gastro-brennecke.de\\\/nico-brennecke-experte-hobbybrauen-schanktechnik\\\/\"],\"url\":\"https:\\\/\\\/gastro-brennecke.de\\\/blog\\\/author\\\/nico\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rumkugel Lik\u00f6r - der Anspruchsvolle - Gastro Brennecke Blog","description":"Ohne Thermomix \u2713 Genial lecker \u2713 cremig-kr\u00e4ftiger Geschmack \u2713 Rezept \u2713 Den musst du probiert haben - hier dein Rezept!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/","og_locale":"de_DE","og_type":"article","og_title":"Rumkugel Lik\u00f6r - der Anspruchsvolle - Gastro Brennecke Blog","og_description":"Ohne Thermomix \u2713 Genial lecker \u2713 cremig-kr\u00e4ftiger Geschmack \u2713 Rezept \u2713 Den musst du probiert haben - hier dein Rezept!","og_url":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/","og_site_name":"Gastro Brennecke Blog","article_publisher":"https:\/\/www.facebook.com\/gastrobrennecke","article_published_time":"2021-10-07T14:00:39+00:00","article_modified_time":"2026-04-12T14:39:15+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r.jpg","type":"image\/jpeg"}],"author":"Nico Brennecke","twitter_card":"summary_large_image","twitter_creator":"@GastroBrennecke","twitter_site":"@GastroBrennecke","twitter_misc":{"Verfasst von":"Nico Brennecke","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/#article","isPartOf":{"@id":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/"},"author":{"name":"Nico Brennecke","@id":"https:\/\/gastro-brennecke.de\/blog\/#\/schema\/person\/f08b921dc43532d46c5935307f76c2d5"},"headline":"Rumkugel Lik\u00f6r &#8211; der Anspruchsvolle","datePublished":"2021-10-07T14:00:39+00:00","dateModified":"2026-04-12T14:39:15+00:00","mainEntityOfPage":{"@id":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/"},"wordCount":274,"commentCount":0,"publisher":{"@id":"https:\/\/gastro-brennecke.de\/blog\/#organization"},"image":{"@id":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/#primaryimage"},"thumbnailUrl":"https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r.jpg?wsr","articleSection":["Lik\u00f6r","Lik\u00f6r Rezepte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/","url":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/","name":"Rumkugel Lik\u00f6r - der Anspruchsvolle - Gastro Brennecke Blog","isPartOf":{"@id":"https:\/\/gastro-brennecke.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/#primaryimage"},"image":{"@id":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/#primaryimage"},"thumbnailUrl":"https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r.jpg?wsr","datePublished":"2021-10-07T14:00:39+00:00","dateModified":"2026-04-12T14:39:15+00:00","description":"Ohne Thermomix \u2713 Genial lecker \u2713 cremig-kr\u00e4ftiger Geschmack \u2713 Rezept \u2713 Den musst du probiert haben - hier dein Rezept!","breadcrumb":{"@id":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/#primaryimage","url":"https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r.jpg?wsr","contentUrl":"https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2021\/10\/Rumkugelliko\u0308r.jpg?wsr","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/gastro-brennecke.de\/blog\/likoer\/rumkugel-likoer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gastro-brennecke.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Rumkugel Lik\u00f6r &#8211; der Anspruchsvolle"}]},{"@type":"WebSite","@id":"https:\/\/gastro-brennecke.de\/blog\/#website","url":"https:\/\/gastro-brennecke.de\/blog\/","name":"Gastro Brennecke Blog","description":"Bier selber brauen | Schank &amp; Zapfanlagen - Gastro Brennecke","publisher":{"@id":"https:\/\/gastro-brennecke.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastro-brennecke.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/gastro-brennecke.de\/blog\/#organization","name":"Gastro Brennecke Blog","url":"https:\/\/gastro-brennecke.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gastro-brennecke.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2020\/11\/2020-brennecke-logo.png?wsr","contentUrl":"https:\/\/gastro-brennecke.de\/blog\/wp-content\/uploads\/2020\/11\/2020-brennecke-logo.png?wsr","width":462,"height":136,"caption":"Gastro Brennecke Blog"},"image":{"@id":"https:\/\/gastro-brennecke.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gastrobrennecke","https:\/\/x.com\/GastroBrennecke","https:\/\/www.linkedin.com\/in\/nico-brennecke-770a64217\/","https:\/\/www.pinterest.de\/bierbrauen","https:\/\/www.youtube.com\/user\/gastrokomplett"]},{"@type":"Person","@id":"https:\/\/gastro-brennecke.de\/blog\/#\/schema\/person\/f08b921dc43532d46c5935307f76c2d5","name":"Nico Brennecke","pronouns":"er\/ihm","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/265753c7995506fcc19fd4b8a2ce9183d2515b32050fd9a3548bd671d9f7ca1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/265753c7995506fcc19fd4b8a2ce9183d2515b32050fd9a3548bd671d9f7ca1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/265753c7995506fcc19fd4b8a2ce9183d2515b32050fd9a3548bd671d9f7ca1a?s=96&d=mm&r=g","caption":"Nico Brennecke"},"description":"Ich bin Nico Brennecke, Experte f\u00fcr Hobbybrauen und Schanktechnik und Inhaber von Gastro Brennecke mit \u00fcber 15 Jahren Erfahrung. Unser Familienunternehmen besteht seit \u00fcber 40 Jahren und hat sich auf alles rund ums Bier brauen, Zapfanlagen und Ausschanktechnik spezialisiert. Vom Einsteiger bis zur Gastronomie unterst\u00fctze ich t\u00e4glich Kunden bei der Auswahl der passenden Technik und Zutaten. Besonders wichtig ist mir, dass unsere Produkte nicht nur verkauft, sondern auch verstanden werden. Deshalb findest du in unserer Wissenswelt, im Blog und im Lexikon zahlreiche Anleitungen, Tipps und Hintergrundwissen aus der Praxis. Durch meine Erfahrung aus tausenden Kundenprojekten wei\u00df ich genau, worauf es beim Bier brauen und beim perfekten Ausschank wirklich ankommt. Wenn du Fragen rund ums Bier brauen oder Zapfanlagen hast, findest du hier im Blog viele praktische Anleitungen aus der Praxis. Mehr \u00fcber mich erf\u00e4hrst du hier: Zur Expertenseite","sameAs":["https:\/\/gastro-brennecke.de\/nico-brennecke-experte-hobbybrauen-schanktechnik\/"],"url":"https:\/\/gastro-brennecke.de\/blog\/author\/nico\/"}]}},"_links":{"self":[{"href":"https:\/\/gastro-brennecke.de\/blog\/wp-json\/wp\/v2\/posts\/2148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastro-brennecke.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastro-brennecke.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastro-brennecke.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gastro-brennecke.de\/blog\/wp-json\/wp\/v2\/comments?post=2148"}],"version-history":[{"count":8,"href":"https:\/\/gastro-brennecke.de\/blog\/wp-json\/wp\/v2\/posts\/2148\/revisions"}],"predecessor-version":[{"id":2161,"href":"https:\/\/gastro-brennecke.de\/blog\/wp-json\/wp\/v2\/posts\/2148\/revisions\/2161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastro-brennecke.de\/blog\/wp-json\/wp\/v2\/media\/4108"}],"wp:attachment":[{"href":"https:\/\/gastro-brennecke.de\/blog\/wp-json\/wp\/v2\/media?parent=2148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastro-brennecke.de\/blog\/wp-json\/wp\/v2\/categories?post=2148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastro-brennecke.de\/blog\/wp-json\/wp\/v2\/tags?post=2148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}